{"id":2693,"date":"2022-09-19T01:20:24","date_gmt":"2022-09-19T01:20:24","guid":{"rendered":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set.jpg"},"modified":"2022-09-19T01:20:24","modified_gmt":"2022-09-19T01:20:24","slug":"ai-art-isometric-set-2","status":"inherit","type":"attachment","link":"https:\/\/bit-jkt.telkomuniversity.ac.id\/en\/ai-art-isometric-set-2\/","title":{"rendered":"dampak-kecerdasan-buatan-dan-kecerdasan-alami-pada-kehidupan-manusia"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-2693","attachment","type-attachment","status-inherit","hentry"],"smush":"Not processed","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled.jpg'><img decoding=\"async\" width=\"300\" height=\"171\" data-src=\"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-300x171.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-300x171.jpg 300w, https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-1024x584.jpg 1024w, https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-768x438.jpg 768w, https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-1536x875.jpg 1536w, https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-2048x1167.jpg 2048w, https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-255x145.jpg 255w, https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-600x342.jpg 600w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/171;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1459,"file":"2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled.jpg","filesize":385181,"sizes":{"medium":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-300x171.jpg","width":300,"height":171,"filesize":16270,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-300x171.jpg"},"large":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-1024x584.jpg","width":1024,"height":584,"filesize":102554,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-1024x584.jpg"},"thumbnail":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-150x150.jpg","width":150,"height":150,"filesize":8360,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-150x150.jpg"},"medium_large":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-768x438.jpg","width":768,"height":438,"filesize":65712,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-768x438.jpg"},"1536x1536":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-1536x875.jpg","width":1536,"height":875,"filesize":177681,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-1536x875.jpg"},"2048x2048":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-2048x1167.jpg","width":2048,"height":1167,"filesize":259983,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-2048x1167.jpg"},"thumb_139x89":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-139x89.jpg","width":139,"height":89,"filesize":6091,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-139x89.jpg"},"thumb_277x337":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-277x337.jpg","width":277,"height":337,"filesize":22672,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-277x337.jpg"},"thumb_50x50":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-50x50.jpg","width":50,"height":50,"filesize":2021,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-50x50.jpg"},"thumb_80x80":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-80x80.jpg","width":80,"height":80,"filesize":3503,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-80x80.jpg"},"thumb_263x263":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-263x263.jpg","width":263,"height":263,"filesize":18545,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-263x263.jpg"},"thumb_409x258":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-409x258.jpg","width":409,"height":258,"filesize":28996,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-409x258.jpg"},"thumb_278x178":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-278x178.jpg","width":278,"height":178,"filesize":16549,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-278x178.jpg"},"thumb_554x674":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-554x674.jpg","width":554,"height":674,"filesize":61668,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-554x674.jpg"},"thumb_100x100":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-100x100.jpg","width":100,"height":100,"filesize":4837,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-100x100.jpg"},"thumb_526x526":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-526x526.jpg","width":526,"height":526,"filesize":51245,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-526x526.jpg"},"thumb_818x516":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-818x516.jpg","width":818,"height":516,"filesize":81130,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-818x516.jpg"},"post-thumbnail":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-255x145.jpg","width":255,"height":145,"filesize":12801,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-255x145.jpg"},"thumb_255x255":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-255x255.jpg","width":255,"height":255,"filesize":17559,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-255x255.jpg"},"woocommerce_thumbnail":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-300x300.jpg","width":300,"height":300,"filesize":22591,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-300x300.jpg"},"woocommerce_single":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-600x342.jpg","width":600,"height":342,"filesize":45823,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-600x342.jpg"},"woocommerce_gallery_thumbnail":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-100x100.jpg","width":100,"height":100,"filesize":4837,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled-100x100.jpg"},"full":{"file":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled.jpg","width":2560,"height":1459,"mime_type":"image\/jpeg","source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/bit-jkt.telkomuniversity.ac.id\/wp-content\/uploads\/2022\/09\/2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled.jpg","filename":"2111.i121.009.S.m005.c13.isometric-ai-art-set-scaled.jpg","filesize":385181,"_links":{"self":[{"href":"https:\/\/bit-jkt.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/media\/2693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bit-jkt.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/bit-jkt.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/bit-jkt.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bit-jkt.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/comments?post=2693"}]}}